{"id":6108,"date":"2024-01-19T08:15:01","date_gmt":"2024-01-19T08:15:01","guid":{"rendered":"https:\/\/unika.co.uk\/?p=6108"},"modified":"2024-01-19T08:15:01","modified_gmt":"2024-01-19T08:15:01","slug":"mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee","status":"publish","type":"post","link":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/","title":{"rendered":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Si vous avez d\u00e9j\u00e0 travaill\u00e9 avec des produits de cautionnement instantan\u00e9 qui vous ont d\u00e9\u00e7u, vous pardonnerez le jeu de mots du titre. Dans le monde de l&rsquo;am\u00e9nagement des cuisines, la durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables, et trouver les bons outils et produits pour rendre votre travail plus rapide et plus facile est une t\u00e2che constante. C&rsquo;est l\u00e0 qu&rsquo;intervient MitreBond, un adh\u00e9sif r\u00e9volutionnaire con\u00e7u pour rehausser la qualit\u00e9 de votre travail. Dans cet article, nous allons explorer les avantages de <a href=\"https:\/\/unika.co.uk\/product\/mitrebond\/\">MitreBond<\/a>, comment l&rsquo;utiliser efficacement, ses propri\u00e9t\u00e9s imperm\u00e9ables, sa r\u00e9sistance, et pr\u00e9senter une solution alternative d&rsquo;activateur, <a href=\"https:\/\/unika.co.uk\/product\/unika-mitrepen\/\">MitrePen<\/a>, pour un adh\u00e9sif instantan\u00e9 qui r\u00e9siste \u00e0 l&rsquo;\u00e9preuve du temps.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Comment utiliser la colle instantan\u00e9e MitreBond :<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">MitreBond est r\u00e9put\u00e9 pour sa facilit\u00e9 d&rsquo;application et son adh\u00e9rence instantan\u00e9e. Voici un guide \u00e9tape par \u00e9tape sur la fa\u00e7on de tirer le meilleur parti de cet adh\u00e9sif innovant :<\/span><\/p>\n<p><b>Pr\u00e9paration de la surface :<br \/>\n<\/b>Assurez-vous que les surfaces \u00e0 coller sont propres, s\u00e8ches et exemptes de poussi\u00e8re et de graisse. Des surfaces lisses et bien pr\u00e9par\u00e9es contribuent \u00e0 une liaison plus forte et plus fiable.<\/p>\n<p><b>Application :<br \/>\n<\/b><span style=\"font-weight: 400;\">Appliquer une ou deux gouttes de colle sur un c\u00f4t\u00e9 du joint. Appliquer l&rsquo;activateur MitreBond en a\u00e9rosol de l&rsquo;autre c\u00f4t\u00e9 du joint. Aligner rapidement les deux c\u00f4t\u00e9s et les presser fermement l&rsquo;un contre l&rsquo;autre, maintenir la pression pendant 15 secondes.<\/span><\/p>\n<p><b>Serrage :<br \/>\n<\/b><span style=\"font-weight: 400;\">Aucun serrage n&rsquo;est n\u00e9cessaire ! MitreBond et MitreBond Activator produisent instantan\u00e9ment des joints propres, \u00e9tanches et fins.<\/span><\/p>\n<p><b>Temps de durcissement :<br \/>\n<\/b><span style=\"font-weight: 400;\">MitreBond se targue d&rsquo;un temps de durcissement rapide de 15 secondes.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Le MitreBond est-il \u00e9tanche ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Oui ! MitreBond est formul\u00e9 pour \u00eatre imperm\u00e9able \u00e0 l&rsquo;eau. Cette caract\u00e9ristique le rend particuli\u00e8rement utile dans les cuisines o\u00f9 l&rsquo;exposition \u00e0 l&rsquo;humidit\u00e9 est in\u00e9vitable. Qu&rsquo;il s&rsquo;agisse de coller des plans de travail, des armoires ou d&rsquo;autres \u00e9l\u00e9ments de la cuisine, MitreBond offre un collage instantan\u00e9 fiable et durable qui r\u00e9siste aux d\u00e9fis de l&rsquo;environnement de la cuisine.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Quelle est la solidit\u00e9 de MitreBond ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">MitreBond est connu pour sa r\u00e9sistance exceptionnelle. Une fois durci, il cr\u00e9e un lien qui est non seulement robuste mais aussi durable. La r\u00e9sistance de MitreBond est particuli\u00e8rement cruciale dans les installations de cuisine, o\u00f9 les joints et les raccords doivent r\u00e9sister \u00e0 une utilisation constante et \u00e0 des contraintes potentielles.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">MitrePen : Une alternative instantan\u00e9e et pr\u00e9cise<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Pour une solution encore plus rapide, pensez \u00e0 MitrePen. Cette alternative \u00e0 l&rsquo;activateur en a\u00e9rosol MitreBond offre une adh\u00e9rence instantan\u00e9e en 10 secondes, ce qui permet des applications efficaces et un gain de temps. Id\u00e9al pour les r\u00e9parations rapides et les petits joints, et sans risque de projection, le MitrePen est parfait pour les installateurs de cuisine qui appr\u00e9cient \u00e0 la fois la pr\u00e9cision et la rapidit\u00e9. Il dure \u00e9galement jusqu&rsquo;\u00e0 3 fois plus longtemps que l&rsquo;a\u00e9rosol.  <a href=\"https:\/\/unika.co.uk\/product\/unika-mitrepen\/\">Pour en savoir plus sur MitrePen, cliquez ici.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, dans le domaine de l&rsquo;am\u00e9nagement des cuisines, o\u00f9 la pr\u00e9cision et la durabilit\u00e9 sont primordiales, MitreBond est un alli\u00e9 fiable. Sa facilit\u00e9 d&rsquo;application, ses propri\u00e9t\u00e9s imperm\u00e9ables et sa r\u00e9sistance exceptionnelle en font un choix de premier ordre pour les professionnels. Et pour les cas o\u00f9 le temps est compt\u00e9, le MitrePen permet un collage instantan\u00e9 sans compromettre la qualit\u00e9. Am\u00e9liorez votre travail avec ces adh\u00e9sifs innovants, en vous assurant que vos installations de cuisine ne r\u00e9pondent pas seulement aux attentes de vos clients, mais qu&rsquo;elles les d\u00e9passent.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous avez d\u00e9j\u00e0 travaill\u00e9 avec des produits de cautionnement instantan\u00e9 qui vous ont d\u00e9\u00e7u, vous pardonnerez le jeu de mots du titre. Dans le monde de l&rsquo;am\u00e9nagement des cuisines, la durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables, et trouver les bons outils et produits pour rendre votre travail plus rapide et plus facile [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[113,115],"tags":[],"class_list":["post-6108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adhesifs","category-unika-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika<\/title>\n<meta name=\"description\" content=\"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika\" \/>\n<meta property=\"og:description\" content=\"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/\" \/>\n<meta property=\"og:site_name\" content=\"Unika\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T08:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"matt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"matt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/\"},\"author\":{\"name\":\"matt\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#\\\/schema\\\/person\\\/9cb49de3d7cedc1ea6a66d714f64829d\"},\"headline\":\"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e\",\"datePublished\":\"2024-01-19T08:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/product-main-mitrebond.png\",\"articleSection\":[\"Adh\u00e9sifs\",\"Unika\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/\",\"url\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/\",\"name\":\"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/product-main-mitrebond.png\",\"datePublished\":\"2024-01-19T08:15:01+00:00\",\"description\":\"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/product-main-mitrebond.png\",\"contentUrl\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/product-main-mitrebond.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/\",\"name\":\"Unika\",\"description\":\"Kitchen fitting supplies from Unika\",\"publisher\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#organization\",\"name\":\"Unika\",\"url\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/header-logo-unika-ips-e1612284206405.png\",\"contentUrl\":\"https:\\\/\\\/unika.co.uk\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/header-logo-unika-ips-e1612284206405.png\",\"width\":512,\"height\":115,\"caption\":\"Unika\"},\"image\":{\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unika.co.uk\\\/fr\\\/#\\\/schema\\\/person\\\/9cb49de3d7cedc1ea6a66d714f64829d\",\"name\":\"matt\",\"sameAs\":[\"https:\\\/\\\/unika.co.uk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika","description":"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/","og_locale":"fr_FR","og_type":"article","og_title":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika","og_description":"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.","og_url":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/","og_site_name":"Unika","article_published_time":"2024-01-19T08:15:01+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png","type":"image\/png"}],"author":"matt","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"matt","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#article","isPartOf":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/"},"author":{"name":"matt","@id":"https:\/\/unika.co.uk\/fr\/#\/schema\/person\/9cb49de3d7cedc1ea6a66d714f64829d"},"headline":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e","datePublished":"2024-01-19T08:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/"},"wordCount":637,"publisher":{"@id":"https:\/\/unika.co.uk\/fr\/#organization"},"image":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#primaryimage"},"thumbnailUrl":"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png","articleSection":["Adh\u00e9sifs","Unika"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/","url":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/","name":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e - Unika","isPartOf":{"@id":"https:\/\/unika.co.uk\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#primaryimage"},"image":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#primaryimage"},"thumbnailUrl":"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png","datePublished":"2024-01-19T08:15:01+00:00","description":"La durabilit\u00e9 et la long\u00e9vit\u00e9 ne sont pas n\u00e9gociables. Voici MitreBond, un adh\u00e9sif r\u00e9volutionnaire \u00e0 collage instantan\u00e9 con\u00e7u pour am\u00e9liorer votre travail.","breadcrumb":{"@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#primaryimage","url":"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png","contentUrl":"https:\/\/unika.co.uk\/wp-content\/uploads\/2022\/06\/product-main-mitrebond.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/unika.co.uk\/fr\/mitrebond-et-les-installateurs-de-cuisine-une-liaison-durable-et-instantanee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unika.co.uk\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"MitreBond et les installateurs de cuisine : Une liaison durable et instantan\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/unika.co.uk\/fr\/#website","url":"https:\/\/unika.co.uk\/fr\/","name":"Unika","description":"Kitchen fitting supplies from Unika","publisher":{"@id":"https:\/\/unika.co.uk\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unika.co.uk\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/unika.co.uk\/fr\/#organization","name":"Unika","url":"https:\/\/unika.co.uk\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/unika.co.uk\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/unika.co.uk\/wp-content\/uploads\/2020\/11\/header-logo-unika-ips-e1612284206405.png","contentUrl":"https:\/\/unika.co.uk\/wp-content\/uploads\/2020\/11\/header-logo-unika-ips-e1612284206405.png","width":512,"height":115,"caption":"Unika"},"image":{"@id":"https:\/\/unika.co.uk\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/unika.co.uk\/fr\/#\/schema\/person\/9cb49de3d7cedc1ea6a66d714f64829d","name":"matt","sameAs":["https:\/\/unika.co.uk"]}]}},"_links":{"self":[{"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/posts\/6108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/comments?post=6108"}],"version-history":[{"count":1,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/posts\/6108\/revisions"}],"predecessor-version":[{"id":6114,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/posts\/6108\/revisions\/6114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/media\/697"}],"wp:attachment":[{"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/media?parent=6108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/categories?post=6108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unika.co.uk\/fr\/wp-json\/wp\/v2\/tags?post=6108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}